{"id":59361,"date":"2026-04-14T00:00:00","date_gmt":"2026-04-13T23:00:00","guid":{"rendered":"https:\/\/www.desiblitz.com\/jobs\/job\/health-and-safety-manager\/"},"modified":"2026-04-14T08:42:34","modified_gmt":"2026-04-14T07:42:34","slug":"health-and-safety-manager","status":"publish","type":"job_listing","link":"https:\/\/www.desiblitz.com\/jobs\/job\/health-and-safety-manager\/","title":{"rendered":"Health and Safety Manager"},"content":{"rendered":"<p><strong>Health and Safety Manager (Part Time)<\/strong><\/p>\n<p><strong>Nailsea<\/strong><\/p>\n<p><strong>&pound;45,000 Pro Rata (&pound;27,000 Salary &#8211; &pound;21.63ph) + Life Assurance (4x Salary) + 25 Days Holiday (Pro rata&rsquo;d) + Company Pension<\/strong><\/p>\n<p><strong>24 Hours per Week &ndash; Flexible Working Hours within Monday to Friday<\/strong><\/p>\n<p>Health and Safety Manager required for an industry leading manufacturing company. This is an exciting time to join the business as they are seeing 15% year on year growth and work within a range of industries from pharmaceutical, oil and gas, refineries, utilities etc. This is an ideal role someone looking for a role that offers part time flexible working hours.<\/p>\n<p>Candidates will be experienced H&amp;S professionals and can come from any manufacturing, engineering or technical background. You will hold a relevant H&amp;S qualification such as the NEBOSH diploma (or equivalent).<\/p>\n<p>The successful candidate will be responsible for overseeing all H&amp;S matters including paperwork, including risk assessments, H&amp;S policies and procedures.<\/p>\n<p><strong>Health and Safety Manager Role:<\/strong><\/p>\n<p>&middot; Oversee and manage all HSE activities and paperwork<br \/>&middot; Risk assessments<br \/>&middot; HSE training<br \/>&middot; Support quality management and investigation of non-conformances<br \/>&middot; Possibility of occasional travel<\/p>\n<p><strong>The Health and Safety Manager Candidate:<\/strong><\/p>\n<p>&middot; Experience H&amp;S professional<br \/>&middot; Any industry background &ndash; manufacturing \/ engineering \/ technical or similar<br \/>&middot; NEBOSH diploma (or equivalent \/ similar)<\/p>\n","protected":false},"author":1,"featured_media":59362,"template":"","meta":{"_promoted":"","_job_location":"Nailsea","_application":"https:\/\/www.cv-library.co.uk\/job\/224979496\/Health-and-Safety-Manager?hlkw&s=103904&affid=103904","_company_name":"Luton Bennett","_company_website":"https:\/\/www.cv-library.co.uk\/list-jobs\/238043\/Luton-Bennett","_company_tagline":"","_company_twitter":"","_company_video":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary_currency":"","_job_salary_unit":""},"job-categories":[61],"job-types":[685],"job_listing_tag":[111],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Health and Safety Manager | DESIblitz Jobs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.desiblitz.com\/jobs\/job\/health-and-safety-manager\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Health and Safety Manager | DESIblitz Jobs\" \/>\n<meta property=\"og:description\" content=\"Health and Safety Manager (Part Time) Nailsea &pound;45,000 Pro Rata (&pound;27,000 Salary &#8211; &pound;21.63ph) + Life Assurance (4x Salary) + 25 Days Holiday (Pro rata&rsquo;d) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.desiblitz.com\/jobs\/job\/health-and-safety-manager\/\" \/>\n<meta property=\"og:site_name\" content=\"DESIblitz Jobs\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T07:42:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.desiblitz.com\/jobs\/wp-content\/uploads\/2026\/04\/2c24044962fb4b4a9113be0e0e62d505-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"56\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@desiblitzjobs\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.desiblitz.com\/jobs\/job\/health-and-safety-manager\/\",\"url\":\"https:\/\/www.desiblitz.com\/jobs\/job\/health-and-safety-manager\/\",\"name\":\"Health and Safety Manager | DESIblitz Jobs\",\"isPartOf\":{\"@id\":\"https:\/\/www.desiblitz.com\/jobs\/#website\"},\"datePublished\":\"2026-04-13T23:00:00+00:00\",\"dateModified\":\"2026-04-14T07:42:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.desiblitz.com\/jobs\/job\/health-and-safety-manager\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.desiblitz.com\/jobs\/job\/health-and-safety-manager\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.desiblitz.com\/jobs\/job\/health-and-safety-manager\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.desiblitz.com\/jobs\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jobs\",\"item\":\"https:\/\/www.desiblitz.com\/jobs\/jobs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Health and Safety Manager\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.desiblitz.com\/jobs\/#website\",\"url\":\"https:\/\/www.desiblitz.com\/jobs\/\",\"name\":\"DESIblitz Jobs\",\"description\":\"Diversity in Jobs\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.desiblitz.com\/jobs\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Health and Safety Manager | DESIblitz Jobs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.desiblitz.com\/jobs\/job\/health-and-safety-manager\/","og_locale":"en_GB","og_type":"article","og_title":"Health and Safety Manager | DESIblitz Jobs","og_description":"Health and Safety Manager (Part Time) Nailsea &pound;45,000 Pro Rata (&pound;27,000 Salary &#8211; &pound;21.63ph) + Life Assurance (4x Salary) + 25 Days Holiday (Pro rata&rsquo;d) [&hellip;]","og_url":"https:\/\/www.desiblitz.com\/jobs\/job\/health-and-safety-manager\/","og_site_name":"DESIblitz Jobs","article_modified_time":"2026-04-14T07:42:34+00:00","og_image":[{"width":240,"height":56,"url":"https:\/\/www.desiblitz.com\/jobs\/wp-content\/uploads\/2026\/04\/2c24044962fb4b4a9113be0e0e62d505-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@desiblitzjobs","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.desiblitz.com\/jobs\/job\/health-and-safety-manager\/","url":"https:\/\/www.desiblitz.com\/jobs\/job\/health-and-safety-manager\/","name":"Health and Safety Manager | DESIblitz Jobs","isPartOf":{"@id":"https:\/\/www.desiblitz.com\/jobs\/#website"},"datePublished":"2026-04-13T23:00:00+00:00","dateModified":"2026-04-14T07:42:34+00:00","breadcrumb":{"@id":"https:\/\/www.desiblitz.com\/jobs\/job\/health-and-safety-manager\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.desiblitz.com\/jobs\/job\/health-and-safety-manager\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.desiblitz.com\/jobs\/job\/health-and-safety-manager\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.desiblitz.com\/jobs\/"},{"@type":"ListItem","position":2,"name":"Jobs","item":"https:\/\/www.desiblitz.com\/jobs\/jobs\/"},{"@type":"ListItem","position":3,"name":"Health and Safety Manager"}]},{"@type":"WebSite","@id":"https:\/\/www.desiblitz.com\/jobs\/#website","url":"https:\/\/www.desiblitz.com\/jobs\/","name":"DESIblitz Jobs","description":"Diversity in Jobs","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.desiblitz.com\/jobs\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/www.desiblitz.com\/jobs\/wp-json\/wp\/v2\/job-listings\/59361"}],"collection":[{"href":"https:\/\/www.desiblitz.com\/jobs\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/www.desiblitz.com\/jobs\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/www.desiblitz.com\/jobs\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.desiblitz.com\/jobs\/wp-json\/wp\/v2\/media\/59362"}],"wp:attachment":[{"href":"https:\/\/www.desiblitz.com\/jobs\/wp-json\/wp\/v2\/media?parent=59361"}],"wp:term":[{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/www.desiblitz.com\/jobs\/wp-json\/wp\/v2\/job-categories?post=59361"},{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/www.desiblitz.com\/jobs\/wp-json\/wp\/v2\/job-types?post=59361"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/www.desiblitz.com\/jobs\/wp-json\/wp\/v2\/job_listing_tag?post=59361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}